{"id":245068,"date":"2024-07-04T01:24:00","date_gmt":"2024-07-04T01:24:00","guid":{"rendered":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/shop\/uncategorized\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%8"},"modified":"2024-07-04T01:24:00","modified_gmt":"2024-07-04T01:24:00","slug":"%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12","status":"publish","type":"product","link":"https:\/\/ww1.douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD"},"content":{"rendered":"<h3><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e33\u0e40\u0e1e\u0e32\u0e30<\/strong><\/h3>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07 \u0e23\u0e38\u0e48\u0e19: BKC-TH16RD<br \/>\n\u0e04\u0e27\u0e32\u0e21\u0e08\u0e38\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 : 4&#215;100\u0e21\u0e25.<br \/>\n\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 (\u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35) : 16500<br \/>\nRCF \u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14: 22150xg<br \/>\n\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32: \u0e40\u0e27\u0e25\u0e32\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07 = 1 \u0e19\u0e32\u0e17\u0e35 ~ 99 \u0e19\u0e32\u0e17\u0e35 59 \u0e27\u0e34\u0e19\u0e32\u0e17\u0e35; \u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 = \u0e04\u0e49\u0e32\u0e07<br \/>\n\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 : +\/- 30 \u0e23\u0e2d\u0e1a\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35<br \/>\n\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 : -20C \u0e16\u0e36\u0e07 40C<br \/>\n\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 : +\/-1C<br \/>\n\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e1a\u0e01\u0e27\u0e19 :  &lt;  55\u0e40\u0e14\u0e0b\u0e34\u0e40\u0e1a\u0e25<br \/>\n\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f : AC110\/220V +\/-10% , 50\/60Hz<br \/>\n\u0e02\u0e19\u0e32\u0e14\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e01\u0e27\u0e49\u0e32\u0e07x\u0e22\u0e32\u0e27x\u0e2a\u0e39\u0e07)\u0e21\u0e21 : 350x662x367<br \/>\n\u0e02\u0e19\u0e32\u0e14\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c (\u0e01\u0e27\u0e49\u0e32\u0e07x\u0e22\u0e32\u0e27x\u0e2a\u0e39\u0e07)\u0e21\u0e21 : 750x440x530<br \/>\n\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e23\u0e27\u0e21 (\u0e01\u0e01.) : 50 \u0e41\u0e25\u0e30 70<\/p>\n<p>\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c<br \/>\n \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e41\u0e14\u0e1b\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e1b\u0e23\u0e14\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e32<\/p>\n","protected":false},"excerpt":{"rendered":"<h3><strong>\u0e23\u0e38\u0e48\u0e19: TH16RD<\/strong><\/h3>\n<h3><strong>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34<\/strong><\/h3>\n<ul>\n<li>\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 5 \u0e19\u0e34\u0e49\u0e27 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49<\/li>\n<li>\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e0a\u0e48\u0e27\u0e22\u0e02\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c<\/li>\n<li>9 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 10 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01\u0e15\u0e30\u0e01\u0e2d\u0e19\u0e23\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e48\u0e19\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19<\/li>\n<li>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 15 \u0e0a\u0e38\u0e14 \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49<\/li>\n<li>\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48 AC \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07<\/li>\n<li>\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e14\u0e38\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23<\/li>\n<li>\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e1f\u0e23\u0e35\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e2b\u0e19\u0e35\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07<\/li>\n<li>\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/li>\n<li>\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/li>\n<\/ul>\n","protected":false},"featured_media":243015,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[296],"product_tag":[],"class_list":["post-245068","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-296"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47-12\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:description\" content=\"\u0e23\u0e38\u0e48\u0e19: TH16RD \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34  \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 5 \u0e19\u0e34\u0e49\u0e27 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49  \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e0a\u0e48\u0e27\u0e22\u0e02\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c  9 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 10 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01\u0e15\u0e30\u0e01\u0e2d\u0e19\u0e23\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e48\u0e19\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19  \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 15 \u0e0a\u0e38\u0e14 \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49  \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48 AC \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07  \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e14\u0e38\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23  \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e1f\u0e23\u0e35\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e2b\u0e19\u0e35\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07  \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14  \u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47-12\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww1.douyeebiomed.com\/wp-content\/uploads\/2024\/07\/707-BKC-TH16RD-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/\",\"url\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"isPartOf\":{\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\"},\"datePublished\":\"2024-07-04T01:24:00+00:00\",\"dateModified\":\"2024-07-04T01:24:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\",\"url\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\",\"name\":\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"description\":\"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47-12\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_description":"\u0e23\u0e38\u0e48\u0e19: TH16RD \u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34  \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 5 \u0e19\u0e34\u0e49\u0e27 \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e20\u0e32\u0e1e\u0e44\u0e14\u0e49  \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e0a\u0e48\u0e27\u0e22\u0e02\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e35\u0e48\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c  9 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27 10 \u0e0a\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23\u0e15\u0e01\u0e15\u0e30\u0e01\u0e2d\u0e19\u0e23\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e48\u0e19\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19  \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49 15 \u0e0a\u0e38\u0e14 \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e44\u0e14\u0e49  \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48 AC \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07  \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e14\u0e38\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23  \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e25\u0e07\u0e1f\u0e23\u0e35\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e2b\u0e19\u0e35\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07  \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e01\u0e25\u0e49\u0e40\u0e07\u0e35\u0e22\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e1a\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14  \u0e42\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e","og_url":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47-12\/","og_site_name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_image":[{"width":1000,"height":1000,"url":"https:\/\/ww1.douyeebiomed.com\/wp-content\/uploads\/2024\/07\/707-BKC-TH16RD-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/","url":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","isPartOf":{"@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website"},"datePublished":"2024-07-04T01:24:00+00:00","dateModified":"2024-07-04T01:24:00+00:00","breadcrumb":{"@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b8%ad%e0%b8%b8%e0%b8%9b%e0%b8%81%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b9%83%e0%b8%99%e0%b8%ab%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%9b%e0%b8%8f\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%ab%e0%b8%a7%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%87%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b9%80%e0%b8%a3%e0%b9%87-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e27\u0e35\u0e48\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 TH16RD"}]},{"@type":"WebSite","@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website","url":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/","name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","description":"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product\/245068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/comments?post=245068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media\/243015"}],"wp:attachment":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media?parent=245068"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_cat?post=245068"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_tag?post=245068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}