{"id":245080,"date":"2025-09-12T02:58:24","date_gmt":"2025-09-12T02:58:24","guid":{"rendered":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/shop\/uncategorized\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9"},"modified":"2025-09-12T02:58:24","modified_gmt":"2025-09-12T02:58:24","slug":"%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2","status":"publish","type":"product","link":"https:\/\/ww1.douyeebiomed.com\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/","title":{"rendered":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34<br \/>\n&#8211; AeroTRAK \u0e23\u0e38\u0e48\u0e19 9350: 0.3 &#8211; 20 \u00b5m<br \/>\n&#8211; AeroTRAK \u0e23\u0e38\u0e48\u0e19 9550: 0.5 &#8211; 20 \u00b5m<br \/>\n&#8211; \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25 50 \u0e25\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35<br \/>\n&#8211; \u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 6 \u0e0a\u0e48\u0e2d\u0e07<br \/>\n&#8211; \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO 21501<br \/>\n&#8211; \u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e1e\u0e38\u0e15 USB \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (TCP\/IP)<br \/>\n&#8211; \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49 10,000 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<br \/>\n&#8211; \u0e01\u0e32\u0e23\u0e14\u0e39\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (ISO-14644-1, FS-209E \u0e41\u0e25\u0e30 EU GMP)<br \/>\n&#8211; \u0e1b\u0e49\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02 250 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23<br \/>\n&#8211; \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 5.7 \u0e19\u0e34\u0e49\u0e27<br \/>\n&#8211; \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b Microsoft\u00ae Windows\u00ae CE<br \/>\n&#8211; \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e15\u0e31\u0e27<br \/>\n&#8211; \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21\u0e44\u0e2d\u0e2d\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e16\u0e2d\u0e14\u0e44\u0e14\u0e49<br \/>\n&#8211; \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19<br \/>\n&#8211; \u0e15\u0e39\u0e49\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a<br \/>\n&#8211; \u0e41\u0e1a\u0e1a\u0e2a\u0e41\u0e15\u0e19\u0e14\u0e4c\u0e2d\u0e42\u0e25\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01<\/p>\n","protected":false},"featured_media":242613,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[299],"product_tag":[],"class_list":["post-245080","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-299"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e43\u0e19\u0e2d\u0e32\u0e01\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e-2\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:description\" content=\"\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 - AeroTRAK \u0e23\u0e38\u0e48\u0e19 9350: 0.3 - 20 \u00b5m - AeroTRAK \u0e23\u0e38\u0e48\u0e19 9550: 0.5 - 20 \u00b5m  - \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25 50 \u0e25\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35  - \u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 6 \u0e0a\u0e48\u0e2d\u0e07  - \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO 21501  - \u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e1e\u0e38\u0e15 USB \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (TCP\/IP)  - \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49 10,000 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23  - \u0e01\u0e32\u0e23\u0e14\u0e39\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (ISO-14644-1, FS-209E \u0e41\u0e25\u0e30 EU GMP)  - \u0e1b\u0e49\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02 250 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23  - \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 5.7 \u0e19\u0e34\u0e49\u0e27 - \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b Microsoft\u00ae Windows\u00ae CE  - \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e15\u0e31\u0e27  - \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21\u0e44\u0e2d\u0e2d\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e16\u0e2d\u0e14\u0e44\u0e14\u0e49  - \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19  - \u0e15\u0e39\u0e49\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a  - \u0e41\u0e1a\u0e1a\u0e2a\u0e41\u0e15\u0e19\u0e14\u0e4c\u0e2d\u0e42\u0e25\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e43\u0e19\u0e2d\u0e32\u0e01\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e-2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ww1.douyeebiomed.com\/wp-content\/uploads\/2024\/03\/DYC706-01-9X50-PPC-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/\",\"url\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/\",\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"isPartOf\":{\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\"},\"datePublished\":\"2025-09-12T02:58:24+00:00\",\"dateModified\":\"2025-09-12T02:58:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\",\"item\":\"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website\",\"url\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/\",\"name\":\"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48\",\"description\":\"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e43\u0e19\u0e2d\u0e32\u0e01\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e-2\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_description":"\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 - AeroTRAK \u0e23\u0e38\u0e48\u0e19 9350: 0.3 - 20 \u00b5m - AeroTRAK \u0e23\u0e38\u0e48\u0e19 9550: 0.5 - 20 \u00b5m  - \u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25 50 \u0e25\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e19\u0e32\u0e17\u0e35  - \u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 6 \u0e0a\u0e48\u0e2d\u0e07  - \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 ISO 21501  - \u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e1e\u0e38\u0e15 USB \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (TCP\/IP)  - \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e14\u0e49 10,000 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23  - \u0e01\u0e32\u0e23\u0e14\u0e39\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (ISO-14644-1, FS-209E \u0e41\u0e25\u0e30 EU GMP)  - \u0e1b\u0e49\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02 250 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23  - \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2a\u0e35\u0e02\u0e19\u0e32\u0e14 5.7 \u0e19\u0e34\u0e49\u0e27 - \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e0b Microsoft\u00ae Windows\u00ae CE  - \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e15\u0e31\u0e27  - \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21\u0e44\u0e2d\u0e2d\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u0e16\u0e2d\u0e14\u0e44\u0e14\u0e49  - \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19  - \u0e15\u0e39\u0e49\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a  - \u0e41\u0e1a\u0e1a\u0e2a\u0e41\u0e15\u0e19\u0e14\u0e4c\u0e2d\u0e42\u0e25\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e27\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01","og_url":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e43\u0e19\u0e2d\u0e32\u0e01\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e-2\/","og_site_name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","og_image":[{"width":1000,"height":1000,"url":"https:\/\/ww1.douyeebiomed.com\/wp-content\/uploads\/2024\/03\/DYC706-01-9X50-PPC-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/","url":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM - \u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","isPartOf":{"@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website"},"datePublished":"2025-09-12T02:58:24+00:00","dateModified":"2025-09-12T02:58:24+00:00","breadcrumb":{"@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/th\/\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%83%e0%b8%99%e0%b8%ad%e0%b8%b2%e0%b8%81%e0%b8%b2\/%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%99%e0%b8%b1%e0%b8%9a%e0%b8%ad%e0%b8%99%e0%b8%b8%e0%b8%a0%e0%b8%b2%e0%b8%84%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%9e%e0%b8%81%e0%b8%9e-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32","item":"https:\/\/douyeebiomed.com\/th\/%e0%b8%a3%e0%b9%89%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e20\u0e32\u0e04\u0e41\u0e1a\u0e1a\u0e1e\u0e01\u0e1e\u0e32 TSI Aerotrak 50 LPM"}]},{"@type":"WebSite","@id":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/#website","url":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/","name":"\u0e42\u0e14\u0e48\u0e27\u0e22\u0e35\u0e48","description":"\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 Dou Yee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web05-hveudngpgzf9hyf7.southeastasia-01.azurewebsites.net\/vi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"}]}},"_links":{"self":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product\/245080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/comments?post=245080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media\/242613"}],"wp:attachment":[{"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/media?parent=245080"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_cat?post=245080"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ww1.douyeebiomed.com\/th\/wp-json\/wp\/v2\/product_tag?post=245080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}